{"id":7461,"date":"2022-10-27T14:15:40","date_gmt":"2022-10-27T12:15:40","guid":{"rendered":"https:\/\/bedigitaladv.com\/?page_id=7461"},"modified":"2025-09-19T13:34:44","modified_gmt":"2025-09-19T11:34:44","slug":"bedigital-home","status":"publish","type":"page","link":"https:\/\/bedigitaladv.com\/en\/bedigital-home\/","title":{"rendered":"BeDigital Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7461\" class=\"elementor elementor-7461\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d7e0453 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no qodef-elementor-stretch-row-no qodef-elementor-overlay-no\" data-id=\"2d7e0453\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28ba99b1\" data-id=\"28ba99b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d54e657 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2d54e657\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>tu <span style=\"color: #3332ff;\">visi\u00f3n,<\/span> nuestra misi\u00f3n <span style=\"color: #3332ff;\">Creativa<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-660ebc59 elementor-widget__width-auto elementor-invisible elementor-widget elementor-widget-text-path\" data-id=\"660ebc59\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;text&quot;:&quot;Work With Us Work With Us&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_rotateZ_effect&quot;:&quot;yes&quot;,&quot;motion_fx_rotateZ_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:50,&quot;end&quot;:100}},&quot;_animation&quot;:&quot;rotateIn&quot;,&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:24,&quot;sizes&quot;:[]},&quot;link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/bedigitaladv.com\\\/contact-us\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;motion_fx_rotateZ_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-path.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-text-path elementor-animation-rotate\" data-text=\"Work With Us Work With Us\" data-url=\"\/\/bedigitaladv.com\/wp-content\/plugins\/elementor\/assets\/svg-paths\/circle.svg\" data-link-url=\"https:\/\/bedigitaladv.com\/contact-us\/\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10fb5600 elementor-section-full_width elementor-reverse-tablet elementor-section-height-default elementor-section-height-default qodef-elementor-content-no qodef-elementor-stretch-row-no qodef-elementor-overlay-no\" data-id=\"10fb5600\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-401e618\" data-id=\"401e618\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:50,&quot;end&quot;:100}},&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d6cf6f3 animated-fast elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"d6cf6f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Desde 2018, somos una agencia de publicidad con un equipo de videomakers, fot\u00f3grafos y editores distribuidos por toda Europa. Trabajamos con pasi\u00f3n y profesionalismo para ofrecer soluciones creativas y efectivas.<\/strong><\/p><p><strong>En los \u00faltimos dos a\u00f1os, nos hemos especializado en colaborar con influencers y youtubers, creando contenido audiovisual de alta calidad y gestionando redes sociales de manera estrat\u00e9gica. Nuestro objetivo es potenciar su alcance y conectar con su audiencia de forma aut\u00e9ntica.<\/strong><\/p><p><strong>Adem\u00e1s, trabajamos con diversas marcas y empresas en el \u00e1mbito del marketing y la publicidad, gestionando cada detalle de los proyectos de principio a fin. Nos encargamos de todo para que nuestros clientes puedan centrarse en lo que realmente importa.<\/strong><\/p><p><strong>Nuestro enfoque combina creatividad, profesionalismo e innovaci\u00f3n, creando historias impactantes y formatos que marcan la diferencia.<\/strong><\/p><p>Esto es <strong>BeDigitalADV<\/strong>, una forma moderna y avanzada de conquistar tu nicho.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-51109fba\" data-id=\"51109fba\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_translateX_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateX_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:50,&quot;end&quot;:100}},&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b08b71e elementor-widget elementor-widget-image\" data-id=\"b08b71e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV12-768x1024.jpg\" class=\"attachment-large size-large wp-image-8501\" alt=\"\" srcset=\"https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV12-768x1024.jpg 768w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV12-225x300.jpg 225w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV12-1152x1536.jpg 1152w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV12-1536x2048.jpg 1536w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV12-9x12.jpg 9w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV12-500x666.jpg 500w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV12-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c59b9f6 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no qodef-elementor-stretch-row-no qodef-elementor-overlay-no\" data-id=\"4c59b9f6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-378dadde\" data-id=\"378dadde\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:50,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1dfa4eb7 elementor-widget elementor-widget-text-editor\" data-id=\"1dfa4eb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ve las ideas <span style=\"color: #3332ff;\">cobrar vida<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cb55af6 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3cb55af6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>En BeDigital, ser\u00e1s parte del plan desde el primer momento hasta la culminaci\u00f3n del proyecto.<\/strong><\/p><p>Nos comprometemos a mantenerte informado en cada etapa, con total transparencia y atenci\u00f3n al detalle.<\/p><p>Nuestro objetivo es que vivas el proceso con confianza, sabiendo que cada decisi\u00f3n y avance est\u00e1n dise\u00f1ados para alcanzar los mejores resultados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cb5e888 elementor-align-left elementor-mobile-align-left elementor-invisible elementor-widget elementor-widget-button\" data-id=\"6cb5e888\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/bedigitaladv.com\/portfolio\/works\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Nuestros trabajos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1753e001 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no qodef-elementor-stretch-row-no qodef-elementor-overlay-no\" data-id=\"1753e001\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1e41ed1e\" data-id=\"1e41ed1e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66ae25fa elementor-widget elementor-widget-image\" data-id=\"66ae25fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_scale_effect&quot;:&quot;yes&quot;,&quot;motion_fx_scale_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-4,&quot;sizes&quot;:[]},&quot;motion_fx_scale_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:50,&quot;end&quot;:100}},&quot;motion_fx_scale_direction&quot;:&quot;out-in&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"2048\" src=\"https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV6-scaled.jpg\" class=\"attachment-full size-full wp-image-8496\" alt=\"\" srcset=\"https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV6-scaled.jpg 2560w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV6-300x240.jpg 300w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV6-1024x819.jpg 1024w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV6-768x614.jpg 768w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV6-1536x1229.jpg 1536w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV6-2048x1638.jpg 2048w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV6-15x12.jpg 15w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3f2cabf1\" data-id=\"3f2cabf1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4edfc7f6 elementor-widget elementor-widget-image\" data-id=\"4edfc7f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:50,&quot;end&quot;:100}},&quot;motion_fx_translateX_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1179\" height=\"2064\" src=\"https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV15.jpg\" class=\"attachment-full size-full wp-image-8504\" alt=\"\" srcset=\"https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV15.jpg 1179w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV15-171x300.jpg 171w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV15-585x1024.jpg 585w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV15-768x1344.jpg 768w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV15-877x1536.jpg 877w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV15-1170x2048.jpg 1170w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV15-7x12.jpg 7w\" sizes=\"(max-width: 1179px) 100vw, 1179px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22a30a38 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no qodef-elementor-stretch-row-no qodef-elementor-overlay-no\" data-id=\"22a30a38\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-25816515\" data-id=\"25816515\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1409a708 elementor-widget elementor-widget-heading\" data-id=\"1409a708\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pong\u00e1monos creativos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8f552 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"b8f552\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>El arte y la creatividad son el n\u00facleo de nuestras vidas, motores que impulsan la innovaci\u00f3n y la conexi\u00f3n emocional. En BeDigital, hemos encontrado la manera de combinar estos elementos de forma estrat\u00e9gica para crear experiencias \u00fanicas y memorables.<\/strong><\/p><p><strong>Nuestro trabajo no solo se trata de producir contenido; se trata de marcar momentos significativos a trav\u00e9s de la creatividad y el dise\u00f1o. Con un enfoque en el entretenimiento, transformamos ideas en historias poderosas que las personas disfrutan y comparten, generando un impacto duradero y aut\u00e9ntico.<\/strong><\/p><p><strong>En BeDigital, entendemos que el arte y la creatividad no solo construyen puentes entre las marcas y su audiencia, sino que tambi\u00e9n generan conexiones profundas que inspiran, emocionan y trascienden fronteras.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-416b409c elementor-invisible elementor-widget elementor-widget-button\" data-id=\"416b409c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/bedigitaladv.com\/contact-us\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">contacto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acd7cd1 elementor-widget__width-auto elementor-widget elementor-widget-text-path\" data-id=\"acd7cd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;text&quot;:&quot;Work With Us Work With Us&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_rotateZ_effect&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;tablet&quot;,&quot;mobile&quot;],&quot;link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/bedigitaladv.com\\\/contact-us\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;motion_fx_rotateZ_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_rotateZ_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}}}\" data-widget_type=\"text-path.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-text-path elementor-animation-rotate\" data-text=\"Work With Us Work With Us\" data-url=\"\/\/bedigitaladv.com\/wp-content\/plugins\/elementor\/assets\/svg-paths\/circle.svg\" data-link-url=\"https:\/\/bedigitaladv.com\/contact-us\/\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-14063e8e\" data-id=\"14063e8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47b846b3 elementor-widget elementor-widget-image\" data-id=\"47b846b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:50}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;],&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1703\" src=\"https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV1-scaled.jpg\" class=\"attachment-full size-full wp-image-8491\" alt=\"\" srcset=\"https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV1-scaled.jpg 2560w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV1-300x200.jpg 300w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV1-1024x681.jpg 1024w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV1-768x511.jpg 768w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV1-1536x1022.jpg 1536w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV1-2048x1363.jpg 2048w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV1-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a62e5cc elementor-widget elementor-widget-image\" data-id=\"a62e5cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BeDigital-21-1024x768.jpg\" class=\"attachment-large size-large wp-image-8513\" alt=\"\" srcset=\"https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BeDigital-21-1024x768.jpg 1024w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BeDigital-21-300x225.jpg 300w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BeDigital-21-768x576.jpg 768w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BeDigital-21-16x12.jpg 16w, https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BeDigital-21.jpg 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37cc4c0a elementor-widget elementor-widget-heading\" data-id=\"37cc4c0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u00a9 2026 BeDigitalAdv. All Rights Reserved.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fefb467 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no qodef-elementor-stretch-row-no qodef-elementor-overlay-no\" data-id=\"fefb467\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-77c82d9\" data-id=\"77c82d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1569c20 elementor-shape-circle e-grid-align-right elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"1569c20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-8345d21\" href=\"https:\/\/www.linkedin.com\/company\/bedigitaladv\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-067e569\" href=\"https:\/\/www.facebook.com\/profile.php?id=100089334742910\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-13a25fc\" href=\"https:\/\/www.instagram.com\/bedigital_adv\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>tu visi\u00f3n, nuestra misi\u00f3n Creativa Desde 2018, somos una agencia de publicidad con un equipo de videomakers, fot\u00f3grafos y editores [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-7461","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BeDigitalAdv | Produzione audiovisiva a Milano e in tutta Europa<\/title>\n<meta name=\"description\" content=\"Casa di produzione audiovisiva. Video corporate, eventi, social. Formati 4K vertical\/orizzontale. Team internazionale. Preventivo in 24h.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bedigitaladv.com\/en\/bedigital-home\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BeDigitalAdv | Produzione audiovisiva a Milano e in tutta Europa\" \/>\n<meta property=\"og:description\" content=\"Casa di produzione audiovisiva. Video corporate, eventi, social. Formati 4K vertical\/orizzontale. Team internazionale. Preventivo in 24h.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bedigitaladv.com\/en\/bedigital-home\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Bedigitaladv\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-19T11:34:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV12-768x1024.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bedigitaladv.com\\\/bedigital-home\\\/\",\"url\":\"https:\\\/\\\/bedigitaladv.com\\\/bedigital-home\\\/\",\"name\":\"BeDigitalAdv | Produzione audiovisiva a Milano e in tutta Europa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bedigitaladv.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bedigitaladv.com\\\/bedigital-home\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bedigitaladv.com\\\/bedigital-home\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bedigitaladv.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/BEDIGITALADV12-768x1024.jpg\",\"datePublished\":\"2022-10-27T12:15:40+00:00\",\"dateModified\":\"2025-09-19T11:34:44+00:00\",\"description\":\"Casa di produzione audiovisiva. Video corporate, eventi, social. Formati 4K vertical\\\/orizzontale. Team internazionale. Preventivo in 24h.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bedigitaladv.com\\\/bedigital-home\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bedigitaladv.com\\\/bedigital-home\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/bedigitaladv.com\\\/bedigital-home\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bedigitaladv.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/BEDIGITALADV12-768x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/bedigitaladv.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/BEDIGITALADV12-768x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bedigitaladv.com\\\/bedigital-home\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bedigitaladv.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BeDigital Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bedigitaladv.com\\\/#website\",\"url\":\"https:\\\/\\\/bedigitaladv.com\\\/\",\"name\":\"Bedigitaladv\",\"description\":\"Agencia de Publicidad y Marketing\",\"publisher\":{\"@id\":\"https:\\\/\\\/bedigitaladv.com\\\/#organization\"},\"alternateName\":\"Bedigitaladv.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bedigitaladv.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bedigitaladv.com\\\/#organization\",\"name\":\"Bedigitaladv\",\"alternateName\":\"Bedigitaladv.com\",\"url\":\"https:\\\/\\\/bedigitaladv.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/bedigitaladv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/bedigitaladv.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo-be-digital-white.png?fit=4506%2C4506&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/bedigitaladv.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo-be-digital-white.png?fit=4506%2C4506&ssl=1\",\"width\":4506,\"height\":4506,\"caption\":\"Bedigitaladv\"},\"image\":{\"@id\":\"https:\\\/\\\/bedigitaladv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Bedigitaladv\\\/\",\"https:\\\/\\\/www.instagram.com\\\/bedigital_adv\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bedigitaladv\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BeDigitalAdv | Produzione audiovisiva a Milano e in tutta Europa","description":"Casa di produzione audiovisiva. Video corporate, eventi, social. Formati 4K vertical\/orizzontale. Team internazionale. Preventivo in 24h.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bedigitaladv.com\/en\/bedigital-home\/","og_locale":"en_GB","og_type":"article","og_title":"BeDigitalAdv | Produzione audiovisiva a Milano e in tutta Europa","og_description":"Casa di produzione audiovisiva. Video corporate, eventi, social. Formati 4K vertical\/orizzontale. Team internazionale. Preventivo in 24h.","og_url":"https:\/\/bedigitaladv.com\/en\/bedigital-home\/","article_publisher":"https:\/\/www.facebook.com\/Bedigitaladv\/","article_modified_time":"2025-09-19T11:34:44+00:00","og_image":[{"url":"https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV12-768x1024.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bedigitaladv.com\/bedigital-home\/","url":"https:\/\/bedigitaladv.com\/bedigital-home\/","name":"BeDigitalAdv | Produzione audiovisiva a Milano e in tutta Europa","isPartOf":{"@id":"https:\/\/bedigitaladv.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bedigitaladv.com\/bedigital-home\/#primaryimage"},"image":{"@id":"https:\/\/bedigitaladv.com\/bedigital-home\/#primaryimage"},"thumbnailUrl":"https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV12-768x1024.jpg","datePublished":"2022-10-27T12:15:40+00:00","dateModified":"2025-09-19T11:34:44+00:00","description":"Casa di produzione audiovisiva. Video corporate, eventi, social. Formati 4K vertical\/orizzontale. Team internazionale. Preventivo in 24h.","breadcrumb":{"@id":"https:\/\/bedigitaladv.com\/bedigital-home\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bedigitaladv.com\/bedigital-home\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/bedigitaladv.com\/bedigital-home\/#primaryimage","url":"https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV12-768x1024.jpg","contentUrl":"https:\/\/bedigitaladv.com\/wp-content\/uploads\/2025\/09\/BEDIGITALADV12-768x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/bedigitaladv.com\/bedigital-home\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bedigitaladv.com\/"},{"@type":"ListItem","position":2,"name":"BeDigital Home"}]},{"@type":"WebSite","@id":"https:\/\/bedigitaladv.com\/#website","url":"https:\/\/bedigitaladv.com\/","name":"Bedigitaladv","description":"Agencia de Publicidad y Marketing","publisher":{"@id":"https:\/\/bedigitaladv.com\/#organization"},"alternateName":"Bedigitaladv.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bedigitaladv.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/bedigitaladv.com\/#organization","name":"Bedigitaladv","alternateName":"Bedigitaladv.com","url":"https:\/\/bedigitaladv.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/bedigitaladv.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/bedigitaladv.com\/wp-content\/uploads\/2025\/01\/logo-be-digital-white.png?fit=4506%2C4506&ssl=1","contentUrl":"https:\/\/i0.wp.com\/bedigitaladv.com\/wp-content\/uploads\/2025\/01\/logo-be-digital-white.png?fit=4506%2C4506&ssl=1","width":4506,"height":4506,"caption":"Bedigitaladv"},"image":{"@id":"https:\/\/bedigitaladv.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Bedigitaladv\/","https:\/\/www.instagram.com\/bedigital_adv\/","https:\/\/www.linkedin.com\/company\/bedigitaladv"]}]}},"_links":{"self":[{"href":"https:\/\/bedigitaladv.com\/en\/wp-json\/wp\/v2\/pages\/7461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bedigitaladv.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bedigitaladv.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bedigitaladv.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bedigitaladv.com\/en\/wp-json\/wp\/v2\/comments?post=7461"}],"version-history":[{"count":198,"href":"https:\/\/bedigitaladv.com\/en\/wp-json\/wp\/v2\/pages\/7461\/revisions"}],"predecessor-version":[{"id":8536,"href":"https:\/\/bedigitaladv.com\/en\/wp-json\/wp\/v2\/pages\/7461\/revisions\/8536"}],"wp:attachment":[{"href":"https:\/\/bedigitaladv.com\/en\/wp-json\/wp\/v2\/media?parent=7461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}